{"id":73,"count":3,"description":"La sociolog\u00eda del g\u00e9nero es el estudio de las relaciones de g\u00e9nero (o de la relaci\u00f3n entre hombres y mujeres, y entre el sexo y el g\u00e9nero) en una sociedad determinada.","link":"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero","name":"Sociolog\u00eda del g\u00e9nero","slug":"sociologia-genero","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sociolog\u00eda del g\u00e9nero<\/title>\n<meta name=\"description\" content=\"Sociolog\u00eda del g\u00e9nero es el estudio de las relaciones de g\u00e9nero (o de la relaci\u00f3n entre hombres y mujeres, y entre sexo y g\u00e9nero) en una sociedad dada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sociolog\u00eda del g\u00e9nero\" \/>\n<meta property=\"og:description\" content=\"Sociolog\u00eda del g\u00e9nero es el estudio de las relaciones de g\u00e9nero (o de la relaci\u00f3n entre hombres y mujeres, y entre sexo y g\u00e9nero) en una sociedad dada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero\" \/>\n<meta property=\"og:site_name\" content=\"Xavier Gimeno Torrent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Xavier_Gimeno\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/es\\\/category\\\/sociologia-genero\",\"url\":\"https:\\\/\\\/xaviergimeno.net\\\/es\\\/category\\\/sociologia-genero\",\"name\":\"Sociolog\u00eda del g\u00e9nero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/#website\"},\"description\":\"Sociolog\u00eda del g\u00e9nero es el estudio de las relaciones de g\u00e9nero (o de la relaci\u00f3n entre hombres y mujeres, y entre sexo y g\u00e9nero) en una sociedad dada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/es\\\/category\\\/sociologia-genero#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/es\\\/category\\\/sociologia-genero#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xaviergimeno.net\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sociolog\u00eda del g\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/#website\",\"url\":\"https:\\\/\\\/xaviergimeno.net\\\/\",\"name\":\"Xavier Gimeno Torrent\",\"description\":\"soci\u00f3logo y traductor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xaviergimeno.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sociolog\u00eda del g\u00e9nero","description":"Sociolog\u00eda del g\u00e9nero es el estudio de las relaciones de g\u00e9nero (o de la relaci\u00f3n entre hombres y mujeres, y entre sexo y g\u00e9nero) en una sociedad dada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero","og_locale":"es_ES","og_type":"article","og_title":"Sociolog\u00eda del g\u00e9nero","og_description":"Sociolog\u00eda del g\u00e9nero es el estudio de las relaciones de g\u00e9nero (o de la relaci\u00f3n entre hombres y mujeres, y entre sexo y g\u00e9nero) en una sociedad dada.","og_url":"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero","og_site_name":"Xavier Gimeno Torrent","twitter_card":"summary_large_image","twitter_site":"@Xavier_Gimeno","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero","url":"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero","name":"Sociolog\u00eda del g\u00e9nero","isPartOf":{"@id":"https:\/\/xaviergimeno.net\/#website"},"description":"Sociolog\u00eda del g\u00e9nero es el estudio de las relaciones de g\u00e9nero (o de la relaci\u00f3n entre hombres y mujeres, y entre sexo y g\u00e9nero) en una sociedad dada.","breadcrumb":{"@id":"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/xaviergimeno.net\/es\/category\/sociologia-genero#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xaviergimeno.net\/es"},{"@type":"ListItem","position":2,"name":"Sociolog\u00eda del g\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/xaviergimeno.net\/#website","url":"https:\/\/xaviergimeno.net\/","name":"Xavier Gimeno Torrent","description":"soci\u00f3logo y traductor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xaviergimeno.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/xaviergimeno.net\/es\/wp-json\/wp\/v2\/categories\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xaviergimeno.net\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/xaviergimeno.net\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/xaviergimeno.net\/es\/wp-json\/wp\/v2\/posts?categories=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}