{"id":76,"count":2,"description":"Conjunto de cualidades atribuidas socialmente en base a la adscripci\u00f3n sexual de la persona y la forma como inciden en las relaciones sociales y las construyen en una sociedad determinada.","link":"https:\/\/xaviergimeno.net\/es\/tag\/genero","name":"G\u00e9nero","slug":"genero","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G\u00e9nero<\/title>\n<meta name=\"description\" content=\"Cualidades atribuidas socialmente en base al sexo de la persona y la forma como inciden en las relaciones sociales y las construyen en una sociedad dada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xaviergimeno.net\/es\/tag\/genero\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G\u00e9nero\" \/>\n<meta property=\"og:description\" content=\"Cualidades atribuidas socialmente en base al sexo de la persona y la forma como inciden en las relaciones sociales y las construyen en una sociedad dada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xaviergimeno.net\/es\/tag\/genero\" \/>\n<meta property=\"og:site_name\" content=\"Xavier Gimeno Torrent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Xavier_Gimeno\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/es\\\/tag\\\/genero\",\"url\":\"https:\\\/\\\/xaviergimeno.net\\\/es\\\/tag\\\/genero\",\"name\":\"G\u00e9nero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/#website\"},\"description\":\"Cualidades atribuidas socialmente en base al sexo de la persona y la forma como inciden en las relaciones sociales y las construyen en una sociedad dada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/es\\\/tag\\\/genero#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/es\\\/tag\\\/genero#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/xaviergimeno.net\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xaviergimeno.net\\\/#website\",\"url\":\"https:\\\/\\\/xaviergimeno.net\\\/\",\"name\":\"Xavier Gimeno Torrent\",\"description\":\"soci\u00f3logo y traductor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xaviergimeno.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G\u00e9nero","description":"Cualidades atribuidas socialmente en base al sexo de la persona y la forma como inciden en las relaciones sociales y las construyen en una sociedad dada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xaviergimeno.net\/es\/tag\/genero","og_locale":"es_ES","og_type":"article","og_title":"G\u00e9nero","og_description":"Cualidades atribuidas socialmente en base al sexo de la persona y la forma como inciden en las relaciones sociales y las construyen en una sociedad dada.","og_url":"https:\/\/xaviergimeno.net\/es\/tag\/genero","og_site_name":"Xavier Gimeno Torrent","twitter_card":"summary_large_image","twitter_site":"@Xavier_Gimeno","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/xaviergimeno.net\/es\/tag\/genero","url":"https:\/\/xaviergimeno.net\/es\/tag\/genero","name":"G\u00e9nero","isPartOf":{"@id":"https:\/\/xaviergimeno.net\/#website"},"description":"Cualidades atribuidas socialmente en base al sexo de la persona y la forma como inciden en las relaciones sociales y las construyen en una sociedad dada.","breadcrumb":{"@id":"https:\/\/xaviergimeno.net\/es\/tag\/genero#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/xaviergimeno.net\/es\/tag\/genero#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/xaviergimeno.net\/es"},{"@type":"ListItem","position":2,"name":"G\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/xaviergimeno.net\/#website","url":"https:\/\/xaviergimeno.net\/","name":"Xavier Gimeno Torrent","description":"soci\u00f3logo y traductor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xaviergimeno.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/xaviergimeno.net\/es\/wp-json\/wp\/v2\/tags\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xaviergimeno.net\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/xaviergimeno.net\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/xaviergimeno.net\/es\/wp-json\/wp\/v2\/posts?tags=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}